{"id":187922,"date":"2023-06-12T19:56:52","date_gmt":"2023-06-12T17:56:52","guid":{"rendered":"https:\/\/actualidadvalencia.com\/passejantvalencia\/?p=187922"},"modified":"2023-06-12T19:56:54","modified_gmt":"2023-06-12T17:56:54","slug":"el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia","status":"publish","type":"post","link":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/","title":{"rendered":"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Per poc que ens fixem amb una mica d&#8217;atenci\u00f3, amb \u201culls curiosos\u201d, a la porta m\u00e9s antiga que conserva la Catedral de Val\u00e8ncia, la de l\u2019Almoina, podrem descobrir nombroses marques i gravats que apareixen als seus vells carreus. D&#8217;alguns coneixen el seu origen o motiu, per\u00f2 d\u2019altres el desconeixem totalment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre alguns d\u2019ells he parlat en anteriors articles. A continuaci\u00f3 podeu trobar els seus enlla\u00e7os:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-passejant-valencia wp-block-embed-passejant-valencia\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"m6RTX3D1tH\"><a href=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/la-troballa-dun-antic-pictograma-del-davallament-de-jesus-de-la-creu-a-la-porta-de-lalmoina-de-la-catedral-de-valencia\/\">La troballa d&#8217;un antic pictograma del Davallament de Jes\u00fas de la creu, a la porta de l\u2019Almoina de la Catedral de Val\u00e8ncia.<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;La troballa d&#8217;un antic pictograma del Davallament de Jes\u00fas de la creu, a la porta de l\u2019Almoina de la Catedral de Val\u00e8ncia.&#8221; &#8212; Passejant Valencia\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/la-troballa-dun-antic-pictograma-del-davallament-de-jesus-de-la-creu-a-la-porta-de-lalmoina-de-la-catedral-de-valencia\/embed\/#?secret=Q6ou3fq6x2#?secret=m6RTX3D1tH\" data-secret=\"m6RTX3D1tH\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-passejant-valencia wp-block-embed-passejant-valencia\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"ohmpHrC2L1\"><a href=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/la-llegenda-del-botxi-que-afilava-la-seua-destral-a-la-porta-de-la-catedral-de-valencia\/\">La llegenda del botxi que esmolava la seua destral a la porta de la Catedral de Val\u00e8ncia.<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;La llegenda del botxi que esmolava la seua destral a la porta de la Catedral de Val\u00e8ncia.&#8221; &#8212; Passejant Valencia\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/la-llegenda-del-botxi-que-afilava-la-seua-destral-a-la-porta-de-la-catedral-de-valencia\/embed\/#?secret=A4uOgmJcRa#?secret=ohmpHrC2L1\" data-secret=\"ohmpHrC2L1\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-passejant-valencia wp-block-embed-passejant-valencia\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"c5X7GpWFMg\"><a href=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-simbol-de-satan-gravat-a-la-porta-romanica-de-la-catedral-de-valencia\/\">El s\u00edmbol de Satan, gravat a la Porta rom\u00e0nica de la Catedral de Val\u00e8ncia?<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;El s\u00edmbol de Satan, gravat a la Porta rom\u00e0nica de la Catedral de Val\u00e8ncia?&#8221; &#8212; Passejant Valencia\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-simbol-de-satan-gravat-a-la-porta-romanica-de-la-catedral-de-valencia\/embed\/#?secret=rGYQFC8CcU#?secret=c5X7GpWFMg\" data-secret=\"c5X7GpWFMg\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-passejant-valencia wp-block-embed-passejant-valencia\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"8azOnvBk9m\"><a href=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/les-marques-dels-canters-que-van-construir-la-porta-de-lalmoina\/\">Les marques dels picapedrers que van construir la Porta de l&#8217;Almoina de la Catedral.<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Les marques dels picapedrers que van construir la Porta de l&#8217;Almoina de la Catedral.&#8221; &#8212; Passejant Valencia\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/les-marques-dels-canters-que-van-construir-la-porta-de-lalmoina\/embed\/#?secret=HILdFz3Kuz#?secret=8azOnvBk9m\" data-secret=\"8azOnvBk9m\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un dels gravats m\u00e9s curiosos que podem trobar als carreus d&#8217;aquesta porta \u00e9s el d&#8217;un calze. Se situa molt a prop de la porta, en un carreu annexe situat a la seua dreta a poc m\u00e9s d&#8217;un metre d&#8217;al\u00e7ada de terra, per la qual cosa \u00e9s ben visible per a tothom.<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"745\" height=\"472\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/06\/a.jpg\" alt=\"\" class=\"wp-image-188183\" srcset=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/06\/a.jpg 745w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/06\/a-300x190.jpg 300w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/06\/a-150x95.jpg 150w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/06\/a-696x441.jpg 696w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/06\/a-663x420.jpg 663w\" sizes=\"auto, (max-width: 745px) 100vw, 745px\" \/><figcaption class=\"wp-element-caption\">Porta de l&#8217;Almoina. Enquadrat en roig, l&#8217;indret on es pot trobar el calze gravat en un carreu.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> Ac\u00ed teniu l&#8217;enlla\u00e7 a l&#8217;article que vaig escriure fa un temps sobre aquest calze:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-passejant-valencia wp-block-embed-passejant-valencia\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"qSKsD2hrvc\"><a href=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/un-sant-calze-gravat-a-la-porta-de-lalmoina-de-la-catedral\/\">Un Sant Calze gravat a la Porta de l&#8217;Almoina de la Catedral?<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Un Sant Calze gravat a la Porta de l&#8217;Almoina de la Catedral?&#8221; &#8212; Passejant Valencia\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/un-sant-calze-gravat-a-la-porta-de-lalmoina-de-la-catedral\/embed\/#?secret=0ETt3KKgzO#?secret=qSKsD2hrvc\" data-secret=\"qSKsD2hrvc\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Qui i quan es va gravar aquest calze, \u00e9s una cosa que mai no podrem saber, per\u00f2 s\u00ed la probable motivaci\u00f3 que va portar al seu an\u00f2nim autor a fer-ho. Sabem que el Sant Calze, que es postula com la copa en qu\u00e8 va beure Jesucrist durant l&#8217;\u00faltim sopar, va ser lliurada al Cabildo Catedralici de Val\u00e8ncia l&#8217;any 1437 per Alfons V d&#8217;Arag\u00f3, com a senyal per un pr\u00e9stec de 40.000 ducats d&#8217;or que va rebre per part del Cabildo per poder finan\u00e7ar les despeses que li generava la conquesta del Regne de N\u00e0pols. <\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-1024x768.jpg\" alt=\"\" class=\"wp-image-187937\" srcset=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-1024x768.jpg 1024w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-300x225.jpg 300w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-768x576.jpg 768w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-1536x1152.jpg 1536w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-2048x1536.jpg 2048w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-150x113.jpg 150w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-696x522.jpg 696w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-1068x801.jpg 1068w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-1920x1440.jpg 1920w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-560x420.jpg 560w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-80x60.jpg 80w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-265x198.jpg 265w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/20221119_104503-1320x990.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-14.jpg\" alt=\"\" class=\"wp-image-187934\" width=\"509\" height=\"665\" srcset=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-14.jpg 457w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-14-230x300.jpg 230w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-14-150x196.jpg 150w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-14-300x392.jpg 300w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-14-322x420.jpg 322w\" sizes=\"auto, (max-width: 509px) 100vw, 509px\" \/><figcaption class=\"wp-element-caption\">Calze gravat en un carreu annexe a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia (Fotografies pr\u00f2pies).<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-16.jpg\" alt=\"\" class=\"wp-image-187938\" width=\"507\" height=\"662\" srcset=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-16.jpg 457w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-16-230x300.jpg 230w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-16-150x196.jpg 150w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-16-300x392.jpg 300w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a-16-322x420.jpg 322w\" sizes=\"auto, (max-width: 507px) 100vw, 507px\" \/><figcaption class=\"wp-element-caption\">Representaci\u00f3 virtual del calze gravat en un carreu de la porta de la Catedral (font pr\u00f2p\u00eca).<\/figcaption><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-image alignfull size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"620\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-5.jpg\" alt=\"\" class=\"wp-image-187924\" srcset=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-5.jpg 768w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-5-300x242.jpg 300w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-5-150x121.jpg 150w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-5-696x562.jpg 696w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-5-520x420.jpg 520w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">El Calze, a la Catedral de Val\u00e8ncia (Font. Catedral de Val\u00e8ncia).<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Podem suposar que l&#8217;autor del gravat ho va fer amb posterioritat a aquesta data, potser per tenir-lo ben present quan la Catedral romania tancada i el p\u00fablic devot del calze no el podia contemplar ni pregar. Per\u00f2 aix\u00f2, per descomptat, \u00e9s nom\u00e9s una suposici\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jean Laurent va ser un fot\u00f2graf franc\u00e8s, dels m\u00e9s importants que van treballar a Espanya durant el segle XIX. Es va establir a Madrid l&#8217;any 1843, per\u00f2 no va comen\u00e7ar a interessar-se seriosament per la fotografia fins a l&#8217;any 1855. L&#8217;any 1857 comen\u00e7\u00e0 a viatjar fora de la capital, on va fer fotografies a moltes ciutats espanyoles. Tamb\u00e9 va comissionar diversos fotografs com ara Julio Arnaud, que entre els anys 1870 i 1872 va visitar diverses ciutats del mediterrani, des de M\u00farcia a Barcelona, entre elles Val\u00e8ncia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Julio Arnaud va fer a Val\u00e8ncia nombroses fotografies per a l&#8217;estudi de Jean Laurent. Entre elles una de la porta de l&#8217;Almoina de la Catedral en qu\u00e8, com a curiositat, aquest calze apareix clarament retratat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ac\u00ed podeu veure aqueixa fotografia:<\/p>\n\n\n\n<figure class=\"wp-block-image alignfull size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"759\" height=\"1024\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-759x1024.jpg\" alt=\"\" class=\"wp-image-187928\" srcset=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-759x1024.jpg 759w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-222x300.jpg 222w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-768x1036.jpg 768w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-1139x1536.jpg 1139w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-150x202.jpg 150w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-300x405.jpg 300w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-696x939.jpg 696w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-1068x1441.jpg 1068w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8-311x420.jpg 311w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-8.jpg 1186w\" sizes=\"auto, (max-width: 759px) 100vw, 759px\" \/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1.jpg.png\" alt=\"\" class=\"wp-image-187929\" width=\"443\" height=\"335\" srcset=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1.jpg.png 372w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1.jpg-300x227.png 300w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1.jpg-150x113.png 150w, https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1.jpg-80x60.png 80w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><figcaption class=\"wp-element-caption\">Calze gravat a la porta rom\u00e0nica, en una fotografia de J. Laurent de l&#8217;any 1870.<\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Un curi\u00f3s calze gravat a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia, retratat en una antiga fotografia&#8230;<\/p>\n","protected":false},"author":140,"featured_media":187925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[845],"tags":[],"class_list":["post-187922","post","type-post","status-publish","format-standard","has-post-thumbnail","category-catedral-de-valencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.<\/title>\n<meta name=\"description\" content=\"Un curi\u00f3s calze gravat a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia, retratat en una antiga fotografia...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.\" \/>\n<meta property=\"og:description\" content=\"Un curi\u00f3s calze gravat a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia, retratat en una antiga fotografia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Passejant Valencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/passejantvalencia\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T17:56:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T17:56:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1186\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis de Manuel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PassejantV\" \/>\n<meta name=\"twitter:site\" content=\"@PassejantV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis de Manuel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/\"},\"author\":{\"name\":\"Luis de Manuel\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#\\\/schema\\\/person\\\/6d4d0a04b0a188eca66a7ab6eb10b2d2\"},\"headline\":\"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.\",\"datePublished\":\"2023-06-12T17:56:52+00:00\",\"dateModified\":\"2023-06-12T17:56:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/\"},\"wordCount\":565,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/a1-6.jpg\",\"articleSection\":[\"Catedral de Val\u00e8ncia\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/\",\"url\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/\",\"name\":\"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/a1-6.jpg\",\"datePublished\":\"2023-06-12T17:56:52+00:00\",\"dateModified\":\"2023-06-12T17:56:54+00:00\",\"description\":\"Un curi\u00f3s calze gravat a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia, retratat en una antiga fotografia...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/a1-6.jpg\",\"contentUrl\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/a1-6.jpg\",\"width\":1186,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#website\",\"url\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/\",\"name\":\"Passejant Valencia\",\"description\":\"M\u00e9s de dos mil\u00b7lennis d&#039;hist\u00f2ria de Val\u00e8ncia, explicats en curts apunts de manera amable per a gent curiosa\",\"publisher\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#organization\"},\"alternateName\":\"Una mirada per la Val\u00e8ncia antiga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#organization\",\"name\":\"Passejant Val\u00e8ncia amb ulls curiosos\",\"url\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Fondo-facebook.png\",\"contentUrl\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Fondo-facebook.png\",\"width\":1024,\"height\":539,\"caption\":\"Passejant Val\u00e8ncia amb ulls curiosos\"},\"image\":{\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/passejantvalencia\",\"https:\\\/\\\/x.com\\\/PassejantV\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/actualidadvalencia.com\\\/passejantvalencia\\\/#\\\/schema\\\/person\\\/6d4d0a04b0a188eca66a7ab6eb10b2d2\",\"name\":\"Luis de Manuel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff5c1b327e17152bcbe98a7db4d565b35f766773476808e987f98e22238fd67e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff5c1b327e17152bcbe98a7db4d565b35f766773476808e987f98e22238fd67e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff5c1b327e17152bcbe98a7db4d565b35f766773476808e987f98e22238fd67e?s=96&d=mm&r=g\",\"caption\":\"Luis de Manuel\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.","description":"Un curi\u00f3s calze gravat a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia, retratat en una antiga fotografia...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/","og_locale":"ca_ES","og_type":"article","og_title":"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.","og_description":"Un curi\u00f3s calze gravat a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia, retratat en una antiga fotografia...","og_url":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/","og_site_name":"Passejant Valencia","article_publisher":"https:\/\/www.facebook.com\/passejantvalencia","article_published_time":"2023-06-12T17:56:52+00:00","article_modified_time":"2023-06-12T17:56:54+00:00","og_image":[{"width":1186,"height":1600,"url":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-6.jpg","type":"image\/jpeg"}],"author":"Luis de Manuel","twitter_card":"summary_large_image","twitter_creator":"@PassejantV","twitter_site":"@PassejantV","twitter_misc":{"Escrit per":"Luis de Manuel","Temps estimat de lectura":"4 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#article","isPartOf":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/"},"author":{"name":"Luis de Manuel","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#\/schema\/person\/6d4d0a04b0a188eca66a7ab6eb10b2d2"},"headline":"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.","datePublished":"2023-06-12T17:56:52+00:00","dateModified":"2023-06-12T17:56:54+00:00","mainEntityOfPage":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/"},"wordCount":565,"commentCount":0,"publisher":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#organization"},"image":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-6.jpg","articleSection":["Catedral de Val\u00e8ncia"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/","url":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/","name":"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia.","isPartOf":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#primaryimage"},"image":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#primaryimage"},"thumbnailUrl":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-6.jpg","datePublished":"2023-06-12T17:56:52+00:00","dateModified":"2023-06-12T17:56:54+00:00","description":"Un curi\u00f3s calze gravat a la porta rom\u00e0nica de la Catedral de Val\u00e8ncia, retratat en una antiga fotografia...","breadcrumb":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#primaryimage","url":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-6.jpg","contentUrl":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2023\/02\/a1-6.jpg","width":1186,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/el-fotograf-jean-laurent-i-el-curios-calze-gravat-en-un-carreu-de-la-porta-romanica-de-la-catedral-de-valencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/actualidadvalencia.com\/passejantvalencia\/"},{"@type":"ListItem","position":2,"name":"El fot\u00f2graf Jean Laurent i el curi\u00f3s calze gravat en un carreu de la porta rom\u00e0nica de la Catedral de Val\u00e8ncia."}]},{"@type":"WebSite","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#website","url":"https:\/\/actualidadvalencia.com\/passejantvalencia\/","name":"Passejant Valencia","description":"M\u00e9s de dos mil\u00b7lennis d&#039;hist\u00f2ria de Val\u00e8ncia, explicats en curts apunts de manera amable per a gent curiosa","publisher":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#organization"},"alternateName":"Una mirada per la Val\u00e8ncia antiga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actualidadvalencia.com\/passejantvalencia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#organization","name":"Passejant Val\u00e8ncia amb ulls curiosos","url":"https:\/\/actualidadvalencia.com\/passejantvalencia\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#\/schema\/logo\/image\/","url":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2018\/05\/Fondo-facebook.png","contentUrl":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-content\/uploads\/2018\/05\/Fondo-facebook.png","width":1024,"height":539,"caption":"Passejant Val\u00e8ncia amb ulls curiosos"},"image":{"@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/passejantvalencia","https:\/\/x.com\/PassejantV"]},{"@type":"Person","@id":"https:\/\/actualidadvalencia.com\/passejantvalencia\/#\/schema\/person\/6d4d0a04b0a188eca66a7ab6eb10b2d2","name":"Luis de Manuel","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/ff5c1b327e17152bcbe98a7db4d565b35f766773476808e987f98e22238fd67e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff5c1b327e17152bcbe98a7db4d565b35f766773476808e987f98e22238fd67e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff5c1b327e17152bcbe98a7db4d565b35f766773476808e987f98e22238fd67e?s=96&d=mm&r=g","caption":"Luis de Manuel"}}]}},"_links":{"self":[{"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/posts\/187922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/comments?post=187922"}],"version-history":[{"count":5,"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/posts\/187922\/revisions"}],"predecessor-version":[{"id":188184,"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/posts\/187922\/revisions\/188184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/media\/187925"}],"wp:attachment":[{"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/media?parent=187922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/categories?post=187922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/actualidadvalencia.com\/passejantvalencia\/wp-json\/wp\/v2\/tags?post=187922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}